{"id":33463,"date":"2022-04-05T13:48:13","date_gmt":"2022-04-05T11:48:13","guid":{"rendered":"https:\/\/praxistrainings-lms.de\/?page_id=33463"},"modified":"2026-03-25T15:39:48","modified_gmt":"2026-03-25T14:39:48","slug":"schulungen-gastronomie","status":"publish","type":"page","link":"https:\/\/praxistrainings-lms.de\/fr\/schulungen-gastronomie\/","title":{"rendered":"Formation hygi\u00e8ne gastronomique"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"33463\" class=\"elementor elementor-33463\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af99841 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af99841\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e99f1c\" data-id=\"9e99f1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab8abf9 elementor-widget elementor-widget-heading\" data-id=\"ab8abf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><b>Gastronomie Hygieneschulung: Schulungen f\u00fcr Gastronomie und Catering<\/b><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fd549d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6fd549d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-05363da\" data-id=\"05363da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-795f2fd elementor-widget__width-inherit elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"795f2fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-fde0d2e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Praxistrainings-LMS_Schulungen-f\u00fcr-Gastronomen\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/praxistrainings-lms.de\/produkt\/lmhv-4-schulung\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Gastronomie Hygieneschulung: LMHV \u00a7 4<\/div><div class=\"elementor-slide-description\"><br><br><br><br>Sie erhalten Ihre gesetzlich vorgeschriebene Schulung nach LMHV \u00a7 4 \u2013 flexibel als E-Learning. Ideal f\u00fcr Einzelpersonen oder Gruppen. Interaktiv und praxisnah gestaltet, sofort verf\u00fcgbar.<br><br>\n6 Stunden \u00b7 E-Learning \u00b7 Sofort starten \u00b7 Teilnahmezertifikat inklusive \u00b7 Gruppenbuchung m\u00f6glich<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Jetzt buchen!<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-3a4f2f1 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"LMHV\u00a74-Milch-Allergen\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/praxistrainings-lms.de\/produkt\/e-learning-allergen-schulung\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Gastronomie Hygieneschulung: Lebensmittel-Allergene<\/div><div class=\"elementor-slide-description\"><br><br><br><br>Erhalten Sie Ihre gesetzlich vorgeschriebene Schulung zu Lebensmittel-Allergenen \u2013 online, kompakt und verst\u00e4ndlich. Auch f\u00fcr Gruppen geeignet.<br><br>\n25 Minuten \u00b7 E-Learning \u00b7 Zertifikat inklusive<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Jetzt buchen!<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-e01bac9 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Infektionsschutzgesetz, Familie sch\u00fctzen\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/praxistrainings-lms.de\/produkt\/folgebelehrung-infektionsschutzgesetz\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Gastronomie Hygieneschulung: Folgebelehrung Infektionsschutzgesetz \u00a7 42, 43<\/div><div class=\"elementor-slide-description\"><br><br><br><br>Erf\u00fcllen Sie die gesetzliche Pflicht zur Folgebelehrung nach \u00a7 42, 43 IfSG \u2013 kompakt, online und mit Zertifikat in nur 25 Minuten. Auch f\u00fcr Gruppen geeignet.<br><br>\n25 Minuten \u00b7 E-Learning \u00b7 Zertifikat inklusive<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Jetzt buchen!<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive pr\u00e9c\u00e9dente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive suivante\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9a7a29 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9a7a29\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f940b7\" data-id=\"4f940b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b9f6db elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4b9f6db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5acedb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5acedb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0d02d3e\" data-id=\"0d02d3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98d412b elementor-widget elementor-widget-image\" data-id=\"98d412b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/elementor\/thumbs\/ld2-py4xdqmdjol8t1h0i4sxv97vb8jmid6o1721nzu0u0.jpg\" title=\"Schulung am Laptop\" alt=\"Mann am Laptop\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-10810bd\" data-id=\"10810bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c0534c elementor-widget elementor-widget-text-editor\" data-id=\"1c0534c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In Deutschland gibt es <b>strenge Gesetze <\/b>f\u00fcr alle Personen, die mit Lebensmitteln arbeiten. Das Ziel ist der <strong>sichere,<\/strong> <b>hygienische Umgang <\/b> mit Lebensmitteln. <br>Wer die Inhalte der Gesetze nicht kennt oder sich nicht daran h\u00e4lt, kann<b> hohe Strafen <\/b>erhalten. <br><br>Mit den E-Learnings von Praxistrainings-LMS erf\u00fcllen Sie Ihre<b> gesetzliche Schulungspflicht zu Lebensmittelsicherheit und Arbeitsschutz<\/b> in Gastronomie und Catering: einfach und von \u00fcberall.<br><\/p>\n<p><\/p>\n<p><span id=\"zoho_button_ext\" style=\"position: absolute;z-index: 99999999;width: 80px;height: 31px;background-size: 80px 31px;cursor: pointer;top: 0px;left: 0px\"><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4e9652 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4e9652\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe2b346\" data-id=\"fe2b346\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25fb53b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"25fb53b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54e81d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54e81d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3b9f10b\" data-id=\"3b9f10b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8efc724 elementor-widget elementor-widget-image\" data-id=\"8efc724\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/elementor\/thumbs\/food-4505944_640-r33jbttng6bovcoiakfjmti2jr17q38vepdsl7ktrs.jpg\" title=\"Essensausgabe\" alt=\"Essensausgabe, Kantine, Warenpr\u00e4sentation\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3544ac3\" data-id=\"3544ac3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cf55e7 elementor-widget elementor-widget-heading\" data-id=\"5cf55e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Unsere Kunden<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f320073 elementor-widget elementor-widget-text-editor\" data-id=\"f320073\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Unsere Kunden stellen Lebensmittel her. Wir arbeiten f\u00fcr Gastronomie, Catering, Gemeinschaftsverpflegung und f\u00fcr Lebensmittel-Hersteller.\u00a0<br \/><span style=\"font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-4);\">Wir bieten Ihnen eine einfache und nachhaltige M\u00f6glichkeit, Ihre Mitarbeiter zu schulen. Dabei k\u00f6nnen Sie unser System nutzen, oder ein im Unternehmen vorhandenes.\u00a0<\/span><a style=\"font-size: 1rem;\" href=\"mailto:elearning@praxistrainings-lms.de\" target=\"_blank\" rel=\"noopener\">Sprechen Sie uns an!<\/a><\/p><p style=\"text-align: left;\"><span style=\"font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-4);\">\u00a0<\/span><\/p><p style=\"text-align: left;\">\u00a0<\/p><p style=\"text-align: left;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9640f67\" data-id=\"9640f67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06d1a4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06d1a4d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b50994\" data-id=\"5b50994\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-330ec77 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"330ec77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2d581c elementor-widget elementor-widget-heading\" data-id=\"a2d581c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Auszug aus den Gastronomie Hygieneschulungen f\u00fcr Gastronomen &amp; Caterer:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1161135 elementor-widget elementor-widget-text-editor\" data-id=\"1161135\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Sie mit Lebensmitteln arbeiten, ben\u00f6tigen Sie <b>laut EU-Vorgabe verschiedene Schulungen.<\/b> Darunter die Lebensmittelhygieneschulung nach \u00a74 LMHV oder die Arbeitsschutzschulung nach Arbeitsschutzgesetz. Mit unseren E-Learnings erhalten Sie Ihr Zertifikat einfach &amp; schnell.<\/p><p>Sie ben\u00f6tigen alle Gastronomie Hygieneschulungen? Dann buchen Sie gerne unser <a href=\"https:\/\/praxistrainings-lms.de\/cartflows_step\/arbeitsschutz-hygienepaket-gastronomie\/\" target=\"_blank\" rel=\"noopener\"><b>Paket f\u00fcr Hygiene &amp; Arbeitsschutz<\/b><\/a>.<\/p><p><span id=\"zoho_button_ext\" style=\"position: absolute;z-index: 99999999;width: 80px;height: 31px;background-size: 80px 31px;cursor: pointer;top: 0px;left: 0px\"><\/span><\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe4b750 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe4b750\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-413b6ef\" data-id=\"413b6ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6bb99c elementor-widget elementor-widget-text-editor\" data-id=\"c6bb99c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" style=\"font-size: 35px;font-style: normal;font-weight: 600;margin-bottom: 0px;color: #ffffff;line-height: 1.2em;font-family: Poppins, sans-serif;text-align: center\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Eingabe hier...\" data-lt-tmp-id=\"lt-775655\" data-gramm=\"false\">Schulungen einzeln buchbar, ab 19 \u20ac pro Person.<\/h2><p style=\"text-align: center\"><strong><span style=\"color: #ffffff\"><\/span><\/strong><span id=\"zoho_button_ext\" style=\"position: absolute;z-index: 99999999;width: 80px;height: 31px;background-size: 80px 31px;cursor: pointer;top: 0px;left: 0px\"><\/span><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b6c558 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b6c558\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c459cba\" data-id=\"c459cba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d1fdb8 elementor-widget elementor-widget-spacer\" data-id=\"0d1fdb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f36024 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f36024\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6835b6\" data-id=\"c6835b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-136643d elementor-widget elementor-widget-heading\" data-id=\"136643d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Aus unserem Schulungs-Angebot f\u00fcr Gastronomie Hygieneschulungen\n<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a594bb elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"0a594bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Unsere Gastronomie Hygieneschulung deckt viele aktuelle Herausforderungen im Bereich Lebensmittelsicherheit und Hygiene ab. Mit E-Learnings k\u00f6nnen Sie diese flexibel durchf\u00fchren. Hier sehen Sie unsere beliebtesten Angebote:<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b0fd24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b0fd24\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d92d13\" data-id=\"9d92d13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8f3aa67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f3aa67\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-87503b0 icon-box-line\" data-id=\"87503b0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2be1c45 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2be1c45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-edit\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M402.3 344.9l32-32c5-5 13.7-1.5 13.7 5.7V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h273.5c7.1 0 10.7 8.6 5.7 13.7l-32 32c-1.5 1.5-3.5 2.3-5.7 2.3H48v352h352V350.5c0-2.1.8-4.1 2.3-5.6zm156.6-201.8L296.3 405.7l-90.4 10c-26.2 2.9-48.5-19.2-45.6-45.6l10-90.4L432.9 17.1c22.9-22.9 59.9-22.9 82.7 0l43.2 43.2c22.9 22.9 22.9 60 .1 82.8zM460.1 174L402 115.9 216.2 301.8l-7.3 65.3 65.3-7.3L460.1 174zm64.8-79.7l-43.2-43.2c-4.1-4.1-10.8-4.1-14.8 0L436 82l58.1 58.1 30.9-30.9c4-4.2 4-10.8-.1-14.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSchulung nach LMHV \u00a7 4\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<br>Gesetzlich vorgeschrieben <br>\nInhalte nach Lebensmittelhygieneverordnung<br>\nMehrere Sprachen\n  <br>\n <br>\n\nca. 6 Stunden E-Learning mit Abschlusstest und Zertifikat\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23bc891 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"23bc891\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/praxistrainings-lms.de\/produkt\/lmhv-4-schulung\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt informieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0696fe2 icon-box-line\" data-id=\"0696fe2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86331e1 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"86331e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-sparkles\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M106.66,170.64l.09,0,49.55-20.65a7.32,7.32,0,0,0,3.68-6h0a7.29,7.29,0,0,0-3.68-6l-49.57-20.67-.07,0L86,67.68a6.66,6.66,0,0,0-11.92,0l-20.7,49.63-.05,0L3.7,138A7.29,7.29,0,0,0,0,144H0a7.32,7.32,0,0,0,3.68,6L53.27,170.6l.07,0L74,220.26a6.65,6.65,0,0,0,11.92,0l20.69-49.62ZM471.38,467.41l-1-.42-1-.5a38.67,38.67,0,0,1,0-69.14l1-.49,1-.43,37.49-15.63,15.63-37.48.41-1,.47-.95c3.85-7.74,10.58-13.63,18.35-17.34,0-1.33.25-2.69.27-4V144a32,32,0,0,0-64,0v72a8,8,0,0,1-8,8H456a8,8,0,0,1-8-8V64a32,32,0,0,0-64,0V216a8,8,0,0,1-8,8H360a8,8,0,0,1-8-8V32a32,32,0,0,0-64,0V216a8,8,0,0,1-8,8H264a8,8,0,0,1-8-8V64a32,32,0,0,0-64,0v241l-23.59-32.49a40,40,0,0,0-64.71,47.09L229.3,492.21A48.07,48.07,0,0,0,268.09,512H465.7c19.24,0,35.65-11.73,43.24-28.79l-.07-.17ZM349.79,339.52,320,351.93l-12.42,29.78a4,4,0,0,1-7.15,0L288,351.93l-29.79-12.41a4,4,0,0,1,0-7.16L288,319.94l12.42-29.78a4,4,0,0,1,7.15,0L320,319.94l29.79,12.42a4,4,0,0,1,0,7.16ZM640,431.91a7.28,7.28,0,0,0-3.68-6l-49.57-20.67-.07,0L566,355.63a6.66,6.66,0,0,0-11.92,0l-20.7,49.63-.05,0L483.7,426a7.28,7.28,0,0,0-3.68,6h0a7.29,7.29,0,0,0,3.68,5.95l49.57,20.67.07,0L554,508.21a6.65,6.65,0,0,0,11.92,0l20.69-49.62h0l.09,0,49.55-20.66a7.29,7.29,0,0,0,3.68-5.95h0Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSchulung Lebensmittel-Hygiene online\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<br>Alle 12 Monate vorgeschrieben <br>\nInhalte nach VO (EG) 852\/2004 <br>\nMehrere Sprachen\n  <br>\n <br>\n\nca. eine Stunde E-Learning mit Abschlusstest und Zertifikat\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-847a100 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"847a100\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/praxistrainings-lms.de\/produkt\/lebensmittelhygiene-schulung\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt informieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6d3accc icon-box-line\" data-id=\"6d3accc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b653d8 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8b653d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bacterium\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M511,102.93A23.76,23.76,0,0,0,481.47,87l-15.12,4.48a111.85,111.85,0,0,0-48.5-47.42l3.79-14.47a23.74,23.74,0,0,0-46-11.91l-3.76,14.37a111.94,111.94,0,0,0-22.33,1.47,386.74,386.74,0,0,0-44.33,10.41l-4.3-12a23.74,23.74,0,0,0-44.75,15.85l4.3,12.05a383.4,383.4,0,0,0-58.69,31.83l-8-10.63a23.85,23.85,0,0,0-33.24-4.8,23.57,23.57,0,0,0-4.83,33.09l8,10.63a386.14,386.14,0,0,0-46.7,47.44l-11-8a23.68,23.68,0,1,0-28,38.17l11.09,8.06a383.45,383.45,0,0,0-30.92,58.75l-12.93-4.43a23.65,23.65,0,1,0-15.47,44.69l13,4.48a385.81,385.81,0,0,0-9.3,40.53A111.58,111.58,0,0,0,32.44,375L17,379.56a23.64,23.64,0,0,0,13.51,45.31l15-4.44a111.49,111.49,0,0,0,48.53,47.24l-3.85,14.75a23.66,23.66,0,0,0,17,28.83,24.7,24.7,0,0,0,6,.75,23.73,23.73,0,0,0,23-17.7L140,479.67c1.37.05,2.77.35,4.13.35A111.22,111.22,0,0,0,205,461.5l11.45,11.74a23.7,23.7,0,0,0,34.08-32.93l-12.19-12.5a111,111,0,0,0,16.11-41.4,158.69,158.69,0,0,1,5.16-20.71l12,5.64a23.66,23.66,0,1,0,20.19-42.79l-11.72-5.49c.89-1.32,1.59-2.77,2.52-4.06a157.86,157.86,0,0,1,10.46-12.49,159.5,159.5,0,0,1,15.59-15.28,162.18,162.18,0,0,1,13.23-10.4c1.5-1,3.1-1.89,4.63-2.87l5.23,11.8a23.74,23.74,0,0,0,43.48-19.08l-5.36-12.11a158.87,158.87,0,0,1,16.49-4.1,111,111,0,0,0,45-18.54l13.33,12a23.69,23.69,0,1,0,31.88-35l-12.94-11.67A110.83,110.83,0,0,0,479.21,137L495,132.32A23.61,23.61,0,0,0,511,102.93ZM160,368a48,48,0,1,1,48-48A48,48,0,0,1,160,368Zm80-136a24,24,0,1,1,24-24A24,24,0,0,1,240,232Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFolgebelehrung IfSG \u00a7 42, 43\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<br>Alle 24 Monate nach Erstbelehrung vorgeschrieben <br>\nInteraktiv <br>\nMehrere Sprachen\n  <br>\n <br>\n\nca. 25 Minuten E-Learning mit Abschlusstest und Zertifikat\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8e22c5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c8e22c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/praxistrainings-lms.de\/produkt\/folgebelehrung-infektionsschutzgesetz\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt informieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-761bc62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"761bc62\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6c5216\" data-id=\"c6c5216\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-457bb9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"457bb9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-48bcf39 icon-box-line\" data-id=\"48bcf39\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd661de elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fd661de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-allergies\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 112c-17.6 0-32 14.4-32 32v72c0 4.4-3.6 8-8 8h-16c-4.4 0-8-3.6-8-8V64c0-17.6-14.4-32-32-32s-32 14.4-32 32v152c0 4.4-3.6 8-8 8h-16c-4.4 0-8-3.6-8-8V32c0-17.6-14.4-32-32-32s-32 14.4-32 32v184c0 4.4-3.6 8-8 8h-16c-4.4 0-8-3.6-8-8V64c0-17.6-14.4-32-32-32S96 46.4 96 64v241l-23.6-32.5c-13-17.9-38-21.8-55.9-8.8s-21.8 38-8.8 55.9l125.6 172.7c9 12.4 23.5 19.8 38.8 19.8h197.6c22.3 0 41.6-15.3 46.7-37l26.5-112.7c3.2-13.7 4.9-28.3 5.1-42.3V144c0-17.6-14.4-32-32-32zM176 416c-8.8 0-16-7.2-16-16s7.2-16 16-16 16 7.2 16 16-7.2 16-16 16zm0-96c-8.8 0-16-7.2-16-16s7.2-16 16-16 16 7.2 16 16-7.2 16-16 16zm64 128c-8.8 0-16-7.2-16-16s7.2-16 16-16 16 7.2 16 16-7.2 16-16 16zm0-96c-8.8 0-16-7.2-16-16s7.2-16 16-16 16 7.2 16 16-7.2 16-16 16zm64 32c-8.8 0-16-7.2-16-16s7.2-16 16-16 16 7.2 16 16-7.2 16-16 16zm32 64c-8.8 0-16-7.2-16-16s7.2-16 16-16 16 7.2 16 16-7.2 16-16 16zm32-128c-8.8 0-16-7.2-16-16s7.2-16 16-16 16 7.2 16 16-7.2 16-16 16z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSchulung Allergene\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<br>Kunden vor allergischen Reaktionen sch\u00fctzen<br>\nInhalte nach Verordnung (EG) 1169\/2011<br>\nMehrere Sprachen\n  <br>\n <br>\n\nca. 25 Minuten E-Learning mit Abschlusstest und Zertifikat\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e78e5f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4e78e5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/praxistrainings-lms.de\/produkt\/e-learning-allergen-schulung\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt informieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6fd31fb icon-box-line\" data-id=\"6fd31fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-313f462 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"313f462\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-exclamation-triangle\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M569.517 440.013C587.975 472.007 564.806 512 527.94 512H48.054c-36.937 0-59.999-40.055-41.577-71.987L246.423 23.985c18.467-32.009 64.72-31.951 83.154 0l239.94 416.028zM288 354c-25.405 0-46 20.595-46 46s20.595 46 46 46 46-20.595 46-46-20.595-46-46-46zm-43.673-165.346l7.418 136c.347 6.364 5.609 11.346 11.982 11.346h48.546c6.373 0 11.635-4.982 11.982-11.346l7.418-136c.375-6.874-5.098-12.654-11.982-12.654h-63.383c-6.884 0-12.356 5.78-11.981 12.654z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tArbeitsschutzschulung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<br>Alle 12 Monate vorgeschrieben <br>\nInhalte nach Arbeitsst\u00e4ttenverordnung &amp; Gefahrstoffverordnung<br>\nMehrere Sprachen\n  <br>\n <br>\n\nca. 45 Minuten E-Learning mit Abschlusstest und Zertifikat\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c1f740 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5c1f740\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/praxistrainings-lms.de\/produkt\/e-learning-arbeitsschutz-schulung\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt informieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-26aaec9 icon-box-line\" data-id=\"26aaec9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b8f22e elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"0b8f22e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bacterium\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M511,102.93A23.76,23.76,0,0,0,481.47,87l-15.12,4.48a111.85,111.85,0,0,0-48.5-47.42l3.79-14.47a23.74,23.74,0,0,0-46-11.91l-3.76,14.37a111.94,111.94,0,0,0-22.33,1.47,386.74,386.74,0,0,0-44.33,10.41l-4.3-12a23.74,23.74,0,0,0-44.75,15.85l4.3,12.05a383.4,383.4,0,0,0-58.69,31.83l-8-10.63a23.85,23.85,0,0,0-33.24-4.8,23.57,23.57,0,0,0-4.83,33.09l8,10.63a386.14,386.14,0,0,0-46.7,47.44l-11-8a23.68,23.68,0,1,0-28,38.17l11.09,8.06a383.45,383.45,0,0,0-30.92,58.75l-12.93-4.43a23.65,23.65,0,1,0-15.47,44.69l13,4.48a385.81,385.81,0,0,0-9.3,40.53A111.58,111.58,0,0,0,32.44,375L17,379.56a23.64,23.64,0,0,0,13.51,45.31l15-4.44a111.49,111.49,0,0,0,48.53,47.24l-3.85,14.75a23.66,23.66,0,0,0,17,28.83,24.7,24.7,0,0,0,6,.75,23.73,23.73,0,0,0,23-17.7L140,479.67c1.37.05,2.77.35,4.13.35A111.22,111.22,0,0,0,205,461.5l11.45,11.74a23.7,23.7,0,0,0,34.08-32.93l-12.19-12.5a111,111,0,0,0,16.11-41.4,158.69,158.69,0,0,1,5.16-20.71l12,5.64a23.66,23.66,0,1,0,20.19-42.79l-11.72-5.49c.89-1.32,1.59-2.77,2.52-4.06a157.86,157.86,0,0,1,10.46-12.49,159.5,159.5,0,0,1,15.59-15.28,162.18,162.18,0,0,1,13.23-10.4c1.5-1,3.1-1.89,4.63-2.87l5.23,11.8a23.74,23.74,0,0,0,43.48-19.08l-5.36-12.11a158.87,158.87,0,0,1,16.49-4.1,111,111,0,0,0,45-18.54l13.33,12a23.69,23.69,0,1,0,31.88-35l-12.94-11.67A110.83,110.83,0,0,0,479.21,137L495,132.32A23.61,23.61,0,0,0,511,102.93ZM160,368a48,48,0,1,1,48-48A48,48,0,0,1,160,368Zm80-136a24,24,0,1,1,24-24A24,24,0,0,1,240,232Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSchulung Mikrobiologie \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<br>Relevante Bakterien beim Umgang mit Lebensmitteln kennen lernen <br>\nMehrere Sprachen\n  <br>\n <br>\n\nca. eine Stunde E-Learning mit Abschlusstest und Zertifikat\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57c96af elementor-align-center elementor-widget elementor-widget-button\" data-id=\"57c96af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/praxistrainings-lms.de\/produkt\/e-learning-mikroorganismen-lebensmittel\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt informieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-926c526 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"926c526\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4bb1ef\" data-id=\"b4bb1ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0355dfb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0355dfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c2044e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c2044e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d14575a\" data-id=\"d14575a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ee2a32 elementor-widget elementor-widget-heading\" data-id=\"3ee2a32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Von Lebensmittelsicherheits-Experten erstellt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60c9751 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"60c9751\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dieses Team aus Praxisexperten hilft Ihnen, Ihre gesetzlichen Pflichten einzuhalten und Ihre Kunden und Mitarbeiter gesund zu halten. Themenbezogen setzten wir weitere TrainerInnen und Fachexperten ein:<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-851edd4 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"851edd4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f7249cc\" data-id=\"f7249cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3115b32 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3115b32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2022\/12\/4181-94a_10x15cm-klein-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-38157\" alt=\"Jennifer Ziegler - HACCP Expertin\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2022\/12\/4181-94a_10x15cm-klein-150x150.jpg 150w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2022\/12\/4181-94a_10x15cm-klein-300x300.jpg 300w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2022\/12\/4181-94a_10x15cm-klein-100x100.jpg 100w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Jennifer Ziegler<\/h3><p class=\"elementor-image-box-description\">E-Learning Design<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb0a2ef elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bb0a2ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d320c2b elementor-widget elementor-widget-text-editor\" data-id=\"d320c2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit viel Liebe zum Thema erstelle ich die Inhalte unserer E-Learnings. Dabei nutze ich Beispiele, Videos, Animationen und Bilder.\u00a0<\/p><p><span id=\"zoho_button_ext\" style=\"position: absolute;z-index: 99999999;width: 80px;height: 31px;background-size: 80px 31px;cursor: pointer;top: 0px;left: 0px\"><\/span><\/p><p><\/p><p><\/p><p><\/p><p><span id=\"zoho_button_ext\" style=\"position: absolute;z-index: 99999999;width: 80px;height: 31px;background-size: 80px 31px;cursor: pointer;top: 0px;left: 0px\"><\/span><\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6265221 e-grid-align-mobile-center e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"6265221\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin-in elementor-repeater-item-c9473de\" href=\"https:\/\/www.linkedin.com\/in\/jennifer-ziegler-sichere-lm\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin-in<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-xing elementor-repeater-item-05c4a92\" href=\"https:\/\/www.xing.com\/profile\/Jennifer_Ziegler10\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Xing<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-xing\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M162.7 210c-1.8 3.3-25.2 44.4-70.1 123.5-4.9 8.3-10.8 12.5-17.7 12.5H9.8c-7.7 0-12.1-7.5-8.5-14.4l69-121.3c.2 0 .2-.1 0-.3l-43.9-75.6c-4.3-7.8.3-14.1 8.5-14.1H100c7.3 0 13.3 4.1 18 12.2l44.7 77.5zM382.6 46.1l-144 253v.3L330.2 466c3.9 7.1.2 14.1-8.5 14.1h-65.2c-7.6 0-13.6-4-18-12.2l-92.4-168.5c3.3-5.8 51.5-90.8 144.8-255.2 4.6-8.1 10.4-12.2 17.5-12.2h65.7c8 0 12.3 6.7 8.5 14.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-link elementor-repeater-item-c7c7031\" href=\"https:\/\/praxistrainings-lms.de\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Link<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-link\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M326.612 185.391c59.747 59.809 58.927 155.698.36 214.59-.11.12-.24.25-.36.37l-67.2 67.2c-59.27 59.27-155.699 59.262-214.96 0-59.27-59.26-59.27-155.7 0-214.96l37.106-37.106c9.84-9.84 26.786-3.3 27.294 10.606.648 17.722 3.826 35.527 9.69 52.721 1.986 5.822.567 12.262-3.783 16.612l-13.087 13.087c-28.026 28.026-28.905 73.66-1.155 101.96 28.024 28.579 74.086 28.749 102.325.51l67.2-67.19c28.191-28.191 28.073-73.757 0-101.83-3.701-3.694-7.429-6.564-10.341-8.569a16.037 16.037 0 0 1-6.947-12.606c-.396-10.567 3.348-21.456 11.698-29.806l21.054-21.055c5.521-5.521 14.182-6.199 20.584-1.731a152.482 152.482 0 0 1 20.522 17.197zM467.547 44.449c-59.261-59.262-155.69-59.27-214.96 0l-67.2 67.2c-.12.12-.25.25-.36.37-58.566 58.892-59.387 154.781.36 214.59a152.454 152.454 0 0 0 20.521 17.196c6.402 4.468 15.064 3.789 20.584-1.731l21.054-21.055c8.35-8.35 12.094-19.239 11.698-29.806a16.037 16.037 0 0 0-6.947-12.606c-2.912-2.005-6.64-4.875-10.341-8.569-28.073-28.073-28.191-73.639 0-101.83l67.2-67.19c28.239-28.239 74.3-28.069 102.325.51 27.75 28.3 26.872 73.934-1.155 101.96l-13.087 13.087c-4.35 4.35-5.769 10.79-3.783 16.612 5.864 17.194 9.042 34.999 9.69 52.721.509 13.906 17.454 20.446 27.294 10.606l37.106-37.106c59.271-59.259 59.271-155.699.001-214.959z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6004860\" data-id=\"6004860\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfa897a elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"dfa897a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/05\/20250504_181146-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-image-66241\" alt=\"Praxistrainings-LMS - Unsere Trainer - Anke Albert\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/05\/20250504_181146-300x300.jpg 300w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/05\/elementor\/thumbs\/20250504_181146-scaled-r5lulug6q5bazckk4ze4fjnwmxsl5z00x0g3s2kb4s.jpg 150w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/05\/20250504_181146-13x12.jpg 13w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/05\/20250504_181146-100x100.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Dr. Anke Albert<\/h3><p class=\"elementor-image-box-description\">Sprachexpertin<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f4d9fa elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6f4d9fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c14aece elementor-widget elementor-widget-text-editor\" data-id=\"c14aece\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left\">Ich sorge daf\u00fcr, dass auch Menschen, die deutsch als Fremdsprache sprechen, die Inhalte von E-Learnings gut verstehen k\u00f6nnen.\u00a0<\/p><p><\/p><p><\/p><p><\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c73dc8d e-grid-align-mobile-center e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"c73dc8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin-in elementor-repeater-item-c9473de\" href=\"https:\/\/www.linkedin.com\/in\/anke-albert-2b398957\/?originalSubdomain=de\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin-in<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-xing elementor-repeater-item-05c4a92\" href=\"https:\/\/www.xing.com\/profile\/Anke_Albert\/cv\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Xing<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-xing\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M162.7 210c-1.8 3.3-25.2 44.4-70.1 123.5-4.9 8.3-10.8 12.5-17.7 12.5H9.8c-7.7 0-12.1-7.5-8.5-14.4l69-121.3c.2 0 .2-.1 0-.3l-43.9-75.6c-4.3-7.8.3-14.1 8.5-14.1H100c7.3 0 13.3 4.1 18 12.2l44.7 77.5zM382.6 46.1l-144 253v.3L330.2 466c3.9 7.1.2 14.1-8.5 14.1h-65.2c-7.6 0-13.6-4-18-12.2l-92.4-168.5c3.3-5.8 51.5-90.8 144.8-255.2 4.6-8.1 10.4-12.2 17.5-12.2h65.7c8 0 12.3 6.7 8.5 14.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2dfe9dc\" data-id=\"2dfe9dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac9f416 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ac9f416\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/10\/Foto-Peter-Stauch_geschnitten-e1640012940970-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-26321\" alt=\"Foto-Peter-Stauch\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/10\/Foto-Peter-Stauch_geschnitten-e1640012940970-150x150.png 150w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/10\/Foto-Peter-Stauch_geschnitten-e1640012940970-100x100.png 100w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Peter Stauch<\/h3><p class=\"elementor-image-box-description\">experte Catering<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d927e4b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d927e4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59c7fc5 elementor-widget elementor-widget-text-editor\" data-id=\"59c7fc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich bringe \u00fcber 30 Jahre Erfahrung im Catering und im Umgang mit Mitarbeitern in die Schulungen ein. Hygiene und Sicherheit sind mein Fokus.<br \/><span id=\"zoho_button_ext\" style=\"position: absolute;z-index: 99999999;width: 80px;height: 31px;background-size: 80px 31px;cursor: pointer;top: 0px;left: 0px\"><\/span><\/p><p><\/p><p><span id=\"zoho_button_ext\" style=\"position: absolute;z-index: 99999999;width: 80px;height: 31px;background-size: 80px 31px;cursor: pointer;top: 0px;left: 0px\"><\/span><\/p><p><\/p><p><\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37681f6 e-grid-align-mobile-center e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"37681f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin-in elementor-repeater-item-c9473de\" href=\"https:\/\/www.linkedin.com\/in\/peter-stauch-473b646a\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin-in<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-xing elementor-repeater-item-05c4a92\" href=\"https:\/\/www.xing.com\/profile\/Peter_Stauch3\/cv\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Xing<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-xing\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M162.7 210c-1.8 3.3-25.2 44.4-70.1 123.5-4.9 8.3-10.8 12.5-17.7 12.5H9.8c-7.7 0-12.1-7.5-8.5-14.4l69-121.3c.2 0 .2-.1 0-.3l-43.9-75.6c-4.3-7.8.3-14.1 8.5-14.1H100c7.3 0 13.3 4.1 18 12.2l44.7 77.5zM382.6 46.1l-144 253v.3L330.2 466c3.9 7.1.2 14.1-8.5 14.1h-65.2c-7.6 0-13.6-4-18-12.2l-92.4-168.5c3.3-5.8 51.5-90.8 144.8-255.2 4.6-8.1 10.4-12.2 17.5-12.2h65.7c8 0 12.3 6.7 8.5 14.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6e09fad\" data-id=\"6e09fad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6fa73c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c6fa73c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/09\/Foto-Andrea-Dreusch-150x150.webp\" class=\"attachment-thumbnail size-thumbnail wp-image-25114\" alt=\"Andrea Dreusch, Referent, Dozent, Experte\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/09\/Foto-Andrea-Dreusch-150x150.webp 150w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/09\/Foto-Andrea-Dreusch-100x100.webp 100w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Andrea Dreusch<\/h3><p class=\"elementor-image-box-description\">expertin Hygiene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4451d9d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4451d9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fd0541 elementor-widget elementor-widget-text-editor\" data-id=\"8fd0541\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left\">Hygiene, Mikrobiologie und verst\u00e4ndliche Schulungen f\u00fcr Mitarbeitende sind meine St\u00e4rken. Mit Passion und Freude am Thema.<\/p><p><span id=\"zoho_button_ext\" style=\"position: absolute;z-index: 99999999;width: 80px;height: 31px;background-size: 80px 31px;cursor: pointer;top: 0px;left: 0px\"><\/span><\/p><p><\/p><p><\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6877514 e-grid-align-mobile-center e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"6877514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin-in elementor-repeater-item-c9473de\" href=\"https:\/\/www.linkedin.com\/in\/andrea-dreusch-86294416\/?originalSubdomain=de\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin-in<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-xing elementor-repeater-item-05c4a92\" href=\"https:\/\/www.xing.com\/profile\/Andrea_Dreusch\/cv\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Xing<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-xing\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M162.7 210c-1.8 3.3-25.2 44.4-70.1 123.5-4.9 8.3-10.8 12.5-17.7 12.5H9.8c-7.7 0-12.1-7.5-8.5-14.4l69-121.3c.2 0 .2-.1 0-.3l-43.9-75.6c-4.3-7.8.3-14.1 8.5-14.1H100c7.3 0 13.3 4.1 18 12.2l44.7 77.5zM382.6 46.1l-144 253v.3L330.2 466c3.9 7.1.2 14.1-8.5 14.1h-65.2c-7.6 0-13.6-4-18-12.2l-92.4-168.5c3.3-5.8 51.5-90.8 144.8-255.2 4.6-8.1 10.4-12.2 17.5-12.2h65.7c8 0 12.3 6.7 8.5 14.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-link elementor-repeater-item-81d0962\" href=\"https:\/\/www.cp-management.de\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Link<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-link\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M326.612 185.391c59.747 59.809 58.927 155.698.36 214.59-.11.12-.24.25-.36.37l-67.2 67.2c-59.27 59.27-155.699 59.262-214.96 0-59.27-59.26-59.27-155.7 0-214.96l37.106-37.106c9.84-9.84 26.786-3.3 27.294 10.606.648 17.722 3.826 35.527 9.69 52.721 1.986 5.822.567 12.262-3.783 16.612l-13.087 13.087c-28.026 28.026-28.905 73.66-1.155 101.96 28.024 28.579 74.086 28.749 102.325.51l67.2-67.19c28.191-28.191 28.073-73.757 0-101.83-3.701-3.694-7.429-6.564-10.341-8.569a16.037 16.037 0 0 1-6.947-12.606c-.396-10.567 3.348-21.456 11.698-29.806l21.054-21.055c5.521-5.521 14.182-6.199 20.584-1.731a152.482 152.482 0 0 1 20.522 17.197zM467.547 44.449c-59.261-59.262-155.69-59.27-214.96 0l-67.2 67.2c-.12.12-.25.25-.36.37-58.566 58.892-59.387 154.781.36 214.59a152.454 152.454 0 0 0 20.521 17.196c6.402 4.468 15.064 3.789 20.584-1.731l21.054-21.055c8.35-8.35 12.094-19.239 11.698-29.806a16.037 16.037 0 0 0-6.947-12.606c-2.912-2.005-6.64-4.875-10.341-8.569-28.073-28.073-28.191-73.639 0-101.83l67.2-67.19c28.239-28.239 74.3-28.069 102.325.51 27.75 28.3 26.872 73.934-1.155 101.96l-13.087 13.087c-4.35 4.35-5.769 10.79-3.783 16.612 5.864 17.194 9.042 34.999 9.69 52.721.509 13.906 17.454 20.446 27.294 10.606l37.106-37.106c59.271-59.259 59.271-155.699.001-214.959z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fd0fb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fd0fb4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e78ae1\" data-id=\"4e78ae1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9df75e elementor-widget elementor-widget-heading\" data-id=\"b9df75e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Sparen Sie jetzt und buchen Sie unser Hygienepaket f\u00fcr nur 45 \u20ac zzgl. MwSt. oder inkl. Arbeitsschutz f\u00fcr 65 \u20ac zzgl. MwSt.!<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa0f270 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"fa0f270\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mit dem Hygienepaket erf\u00fcllen Sie alle rechtlichen Anforderungen zur Lebensmittelsicherheit f\u00fcr die n\u00e4chsten 12 Monate. <br>Begrenztes Angebot!<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b19eb07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b19eb07\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e1ce2b\" data-id=\"6e1ce2b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0d9ada elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e0d9ada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/praxistrainings-lms.de\/cartflows_step\/hygienepaket-kaufen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hygienepaket kaufen: 45 \u20ac<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccc06a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccc06a6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-829e5aa\" data-id=\"829e5aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cb8466 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7cb8466\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/praxistrainings-lms.de\/cartflows_step\/arbeitsschutz-hygienepaket-gastronomie\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hygiene- und Arbeitsschutzpaket kaufen: 65 \u20ac<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c313cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c313cf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-00e7ec2\" data-id=\"00e7ec2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c11653f elementor-widget elementor-widget-heading\" data-id=\"c11653f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vorteile unserer E-Learnings<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01c11d8 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"01c11d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wir helfen Ihnen, Ihre gesetzlichen Pflichten einzuhalten und sicher mit Lebensmitteln umzugehen. Mit unseren Gastronomie Hygieneschulungen zur Lebensmittelsicherheit in Gastronomie, Catering und GV.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ff4d967 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff4d967\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-781c5d0\" data-id=\"781c5d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d75e3b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5d75e3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-clock\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256,8C119,8,8,119,8,256S119,504,256,504,504,393,504,256,393,8,256,8Zm92.49,313h0l-20,25a16,16,0,0,1-22.49,2.5h0l-67-49.72a40,40,0,0,1-15-31.23V112a16,16,0,0,1,16-16h32a16,16,0,0,1,16,16V256l58,42.5A16,16,0,0,1,348.49,321Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tZugriff sofort\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDirekt nach Bezahlung\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-32a3d42\" data-id=\"32a3d42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f7c76a elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3f7c76a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSchnell\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKurze Schulungsdauer\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-fd21bfe\" data-id=\"fd21bfe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b4326b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9b4326b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-pdf\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M181.9 256.1c-5-16-4.9-46.9-2-46.9 8.4 0 7.6 36.9 2 46.9zm-1.7 47.2c-7.7 20.2-17.3 43.3-28.4 62.7 18.3-7 39-17.2 62.9-21.9-12.7-9.6-24.9-23.4-34.5-40.8zM86.1 428.1c0 .8 13.2-5.4 34.9-40.2-6.7 6.3-29.1 24.5-34.9 40.2zM248 160h136v328c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V24C0 10.7 10.7 0 24 0h200v136c0 13.2 10.8 24 24 24zm-8 171.8c-20-12.2-33.3-29-42.7-53.8 4.5-18.5 11.6-46.6 6.2-64.2-4.7-29.4-42.4-26.5-47.8-6.8-5 18.3-.4 44.1 8.1 77-11.6 27.6-28.7 64.6-40.8 85.8-.1 0-.1.1-.2.1-27.1 13.9-73.6 44.5-54.5 68 5.6 6.9 16 10 21.5 10 17.9 0 35.7-18 61.1-61.8 25.8-8.5 54.1-19.1 79-23.2 21.7 11.8 47.1 19.5 64 19.5 29.2 0 31.2-32 19.7-43.4-13.9-13.6-54.3-9.7-73.6-7.2zM377 105L279 7c-4.5-4.5-10.6-7-17-7h-6v128h128v-6.1c0-6.3-2.5-12.4-7-16.9zm-74.1 255.3c4.1-2.7-2.5-11.9-42.8-9 37.1 15.8 42.8 9 42.8 9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tZertifikat\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDirekt als pdf\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-11e74ae\" data-id=\"11e74ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eeab6cc elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"eeab6cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-globe\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M336.5 160C322 70.7 287.8 8 248 8s-74 62.7-88.5 152h177zM152 256c0 22.2 1.2 43.5 3.3 64h185.3c2.1-20.5 3.3-41.8 3.3-64s-1.2-43.5-3.3-64H155.3c-2.1 20.5-3.3 41.8-3.3 64zm324.7-96c-28.6-67.9-86.5-120.4-158-141.6 24.4 33.8 41.2 84.7 50 141.6h108zM177.2 18.4C105.8 39.6 47.8 92.1 19.3 160h108c8.7-56.9 25.5-107.8 49.9-141.6zM487.4 192H372.7c2.1 21 3.3 42.5 3.3 64s-1.2 43-3.3 64h114.6c5.5-20.5 8.6-41.8 8.6-64s-3.1-43.5-8.5-64zM120 256c0-21.5 1.2-43 3.3-64H8.6C3.2 212.5 0 233.8 0 256s3.2 43.5 8.6 64h114.6c-2-21-3.2-42.5-3.2-64zm39.5 96c14.5 89.3 48.7 152 88.5 152s74-62.7 88.5-152h-177zm159.3 141.6c71.4-21.2 129.4-73.7 158-141.6h-108c-8.8 56.9-25.6 107.8-50 141.6zM19.3 352c28.6 67.9 86.5 120.4 158 141.6-24.4-33.8-41.2-84.7-50-141.6h-108z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u00dcbersetzungen*\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t16 Sprachen\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-08e8bfe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08e8bfe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-460b154\" data-id=\"460b154\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-864f0f9 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"864f0f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-grin-beam\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 8C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm0 448c-110.3 0-200-89.7-200-200S137.7 56 248 56s200 89.7 200 200-89.7 200-200 200zm105.6-151.4c-25.9 8.3-64.4 13.1-105.6 13.1s-79.6-4.8-105.6-13.1c-9.8-3.1-19.4 5.3-17.7 15.3 7.9 47.1 71.3 80 123.3 80s115.3-32.9 123.3-80c1.6-9.8-7.7-18.4-17.7-15.3zm-235.9-72.9c3.5 1.1 7.4-.5 9.3-3.7l9.5-17c7.7-13.7 19.2-21.6 31.5-21.6s23.8 7.9 31.5 21.6l9.5 17c2.1 3.7 6.2 4.7 9.3 3.7 3.6-1.1 6-4.5 5.7-8.3-3.3-42.1-32.2-71.4-56-71.4s-52.7 29.3-56 71.4c-.3 3.7 2.1 7.2 5.7 8.3zm160 0c3.5 1.1 7.4-.5 9.3-3.7l9.5-17c7.7-13.7 19.2-21.6 31.5-21.6s23.8 7.9 31.5 21.6l9.5 17c2.1 3.7 6.2 4.7 9.3 3.7 3.6-1.1 6-4.5 5.7-8.3-3.3-42.1-32.2-71.4-56-71.4s-52.7 29.3-56 71.4c-.3 3.7 2.1 7.2 5.7 8.3z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVerst\u00e4ndlich\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tohne Fachchinesisch\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-91ced8a\" data-id=\"91ced8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b30d25 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3b30d25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-play-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M371.7 238l-176-107c-15.8-8.8-35.7 2.5-35.7 21v208c0 18.4 19.8 29.8 35.7 21l176-101c16.4-9.1 16.4-32.8 0-42zM504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInteraktiv\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBilder, Videos, Tests\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-47570bd\" data-id=\"47570bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cb7b40 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7cb7b40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-people-arrows\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M96,128A64,64,0,1,0,32,64,64,64,0,0,0,96,128Zm0,176.08a44.11,44.11,0,0,1,13.64-32L181.77,204c1.65-1.55,3.77-2.31,5.61-3.57A63.91,63.91,0,0,0,128,160H64A64,64,0,0,0,0,224v96a32,32,0,0,0,32,32V480a32,32,0,0,0,32,32h64a32,32,0,0,0,32-32V383.61l-50.36-47.53A44.08,44.08,0,0,1,96,304.08ZM480,128a64,64,0,1,0-64-64A64,64,0,0,0,480,128Zm32,32H448a63.91,63.91,0,0,0-59.38,40.42c1.84,1.27,4,2,5.62,3.59l72.12,68.06a44.37,44.37,0,0,1,0,64L416,383.62V480a32,32,0,0,0,32,32h64a32,32,0,0,0,32-32V352a32,32,0,0,0,32-32V224A64,64,0,0,0,512,160ZM444.4,295.34l-72.12-68.06A12,12,0,0,0,352,236v36H224V236a12,12,0,0,0-20.28-8.73L131.6,295.34a12.4,12.4,0,0,0,0,17.47l72.12,68.07A12,12,0,0,0,224,372.14V336H352v36.14a12,12,0,0,0,20.28,8.74l72.12-68.07A12.4,12.4,0,0,0,444.4,295.34Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tF\u00fcr Gruppen**\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSonderkonditionen\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-285ade2\" data-id=\"285ade2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e55e2b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"0e55e2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-building\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M436 480h-20V24c0-13.255-10.745-24-24-24H56C42.745 0 32 10.745 32 24v456H12c-6.627 0-12 5.373-12 12v20h448v-20c0-6.627-5.373-12-12-12zM128 76c0-6.627 5.373-12 12-12h40c6.627 0 12 5.373 12 12v40c0 6.627-5.373 12-12 12h-40c-6.627 0-12-5.373-12-12V76zm0 96c0-6.627 5.373-12 12-12h40c6.627 0 12 5.373 12 12v40c0 6.627-5.373 12-12 12h-40c-6.627 0-12-5.373-12-12v-40zm52 148h-40c-6.627 0-12-5.373-12-12v-40c0-6.627 5.373-12 12-12h40c6.627 0 12 5.373 12 12v40c0 6.627-5.373 12-12 12zm76 160h-64v-84c0-6.627 5.373-12 12-12h40c6.627 0 12 5.373 12 12v84zm64-172c0 6.627-5.373 12-12 12h-40c-6.627 0-12-5.373-12-12v-40c0-6.627 5.373-12 12-12h40c6.627 0 12 5.373 12 12v40zm0-96c0 6.627-5.373 12-12 12h-40c-6.627 0-12-5.373-12-12v-40c0-6.627 5.373-12 12-12h40c6.627 0 12 5.373 12 12v40zm0-96c0 6.627-5.373 12-12 12h-40c-6.627 0-12-5.373-12-12V76c0-6.627 5.373-12 12-12h40c6.627 0 12 5.373 12 12v40z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tF\u00fcr Unternehmen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAnpassbar***\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-503adff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"503adff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb101f7\" data-id=\"eb101f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a1edb0 elementor-widget elementor-widget-text-editor\" data-id=\"3a1edb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>*<strong> \u00dcbersetzungen:<\/strong> F\u00fcr die \u00dcbersetzungen nutzen wir Google Translate. Nur so k\u00f6nnen wir unsere g\u00fcnstigen Preise halten. Sollte sich einmal der Fehlerteufel einschleichen, dann korrigieren wir diesen gerne. Informieren Sie uns per E-Mail an <a href=\"mailto:info@praxistrainings-lms.de\">info@praxistrainings-lms.de<\/a>). Videos werden auf Deutsch oder Englisch angezeigt.\u00a0Weitere Sprachen f\u00fcgen wir auf Anfrage gerne kostenfrei hinzu.\u00a0<\/p><p>** <b>F\u00fcr Gruppen:<\/b> Melden Sie sich unter <a href=\"mailto:info@praxistrainings-lms.de\">info@praxistrainings-lms.de<\/a> und wir richten Ihnen einen Gruppenzugang ein. Folgende Rabatte gelten f\u00fcr Gruppen: Ab 10 Personen bieten wir 10 % Rabatt auf den Kurspreis an, 30 % Rabatt ab 50 Personen. Weitere auf Anfrage.<\/p><p>***<b> F\u00fcr Unternehmen: <\/b>Arbeiten Sie in einem Lebensmittel-Unternehmen und m\u00f6chten E-Learnings einsetzen? Und dabei Ihre unternehmensinternen Vorgaben umsetzen?\u00a0<span style=\"font-style: inherit;font-weight: inherit;background-color: var(--ast-global-color-4)\">Dann sind wir gerne Ihr Partner. Schreiben Sie an <\/span><a style=\"font-style: inherit;font-weight: inherit\" href=\"mailto:info@praxistrainings-lms.de\">info@praxistrainings-lms.de<\/a><span style=\"font-style: inherit;font-weight: inherit;background-color: var(--ast-global-color-4)\">.\u00a0<\/span><\/p><p><span id=\"zoho_button_ext\" style=\"position: absolute;z-index: 99999999;width: 80px;height: 31px;background-size: 80px 31px;cursor: pointer;top: 0px;left: 0px\"><\/span><\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9066e55 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9066e55\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-190ea27\" data-id=\"190ea27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf25573 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bf25573\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca8736f elementor-widget elementor-widget-heading\" data-id=\"ca8736f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Downloads f\u00fcr die Gastronomie - jetzt herunterladen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63d8181 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"63d8181\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Jetzt herunterladen!<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c25e3e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c25e3e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-86cbb36\" data-id=\"86cbb36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f53d223 elementor-widget elementor-widget-image\" data-id=\"f53d223\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Praxistrainings-LMS_Vorlage-Wareneingangskontrolle-V1.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"249\" height=\"300\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-WE-3D-249x300.png\" class=\"attachment-medium size-medium wp-image-41752\" alt=\"Betriebliche-Eigenkontrolle-Wareneingangskontrolle-3D\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-WE-3D-249x300.png 249w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-WE-3D-600x724.png 600w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-WE-3D-849x1024.png 849w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-WE-3D-768x926.png 768w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-WE-3D-10x12.png 10w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-WE-3D.png 917w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d619c34 elementor-widget elementor-widget-heading\" data-id=\"d619c34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Praxistrainings-LMS_Vorlage-Wareneingangskontrolle-V1.pdf\">Eigenkontrollen: Warenanlieferung<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1461d06\" data-id=\"1461d06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7ec046 elementor-widget elementor-widget-image\" data-id=\"f7ec046\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Praxistrainings-LMS_Vorlage-Kuehleinrichtungen-V1.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"249\" height=\"300\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Kuehleinrichtungen-3D-249x300.png\" class=\"attachment-medium size-medium wp-image-41747\" alt=\"Betriebliche-Eigenkontrolle-K\u00fchleinrichtungen-3D\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Kuehleinrichtungen-3D-249x300.png 249w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Kuehleinrichtungen-3D-600x724.png 600w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Kuehleinrichtungen-3D-849x1024.png 849w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Kuehleinrichtungen-3D-768x926.png 768w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Kuehleinrichtungen-3D-10x12.png 10w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Kuehleinrichtungen-3D.png 917w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee380c1 elementor-widget elementor-widget-heading\" data-id=\"ee380c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Praxistrainings-LMS_Vorlage-Kuehleinrichtungen-V1.pdf\">Eigenkontrollen: Temperaturen K\u00fchleinrichtungen<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-782672c\" data-id=\"782672c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae93567 elementor-widget elementor-widget-image\" data-id=\"ae93567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Praxistrainings-LMS_Vorlage-warme-Kueche-V1.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"249\" height=\"300\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Erhitzung-3D-1-249x300.png\" class=\"attachment-medium size-medium wp-image-41756\" alt=\"Betriebliche-Eigenkontrolle-Erhitzung\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Erhitzung-3D-1-249x300.png 249w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Erhitzung-3D-1-600x724.png 600w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Erhitzung-3D-1-849x1024.png 849w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Erhitzung-3D-1-768x926.png 768w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Erhitzung-3D-1-10x12.png 10w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Erhitzung-3D-1.png 917w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2af002 elementor-widget elementor-widget-heading\" data-id=\"c2af002\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Praxistrainings-LMS_Vorlage-warme-Kueche-V1.pdf\">Eigenkontrollen: Erhitzung<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8a7671c\" data-id=\"8a7671c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13d6042 elementor-widget elementor-widget-image\" data-id=\"13d6042\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Praxistrainings-LMS_Vorlage-Schaedlingskontrolle-V1.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"249\" height=\"300\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Schaedlingskontrolle-3D-249x300.png\" class=\"attachment-medium size-medium wp-image-41749\" alt=\"Betriebliche-Eigenkontrolle-Sch\u00e4dlingskontrolle-3D\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Schaedlingskontrolle-3D-249x300.png 249w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Schaedlingskontrolle-3D-600x724.png 600w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Schaedlingskontrolle-3D-849x1024.png 849w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Schaedlingskontrolle-3D-768x926.png 768w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Schaedlingskontrolle-3D-10x12.png 10w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Binder-Front-1160x1450-Schaedlingskontrolle-3D.png 917w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-098d51d elementor-widget elementor-widget-heading\" data-id=\"098d51d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/05\/Praxistrainings-LMS_Vorlage-Schaedlingskontrolle-V1.pdf\">Eigenkontrollen: Sch\u00e4dlingskontrolle<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e0fa87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e0fa87\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ff179d\" data-id=\"1ff179d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5eea2d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c5eea2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/praxistrainings-lms.de\/downloads-gastronomie\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weitere Gastronomie-Downloads<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2fe22b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2fe22b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11c9558\" data-id=\"11c9558\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbb68f6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bbb68f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab63195 elementor-widget elementor-widget-heading\" data-id=\"ab63195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00e4ufige Fragen zur Gastronomie Hygieneschulung f\u00fcr Gastronomie &amp; Catering\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1fbbc6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1fbbc6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b29ecf\" data-id=\"3b29ecf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae0d766 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ae0d766\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-question-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.043 8 8 119.083 8 256c0 136.997 111.043 248 248 248s248-111.003 248-248C504 119.083 392.957 8 256 8zm0 448c-110.532 0-200-89.431-200-200 0-110.495 89.472-200 200-200 110.491 0 200 89.471 200 200 0 110.53-89.431 200-200 200zm107.244-255.2c0 67.052-72.421 68.084-72.421 92.863V300c0 6.627-5.373 12-12 12h-45.647c-6.627 0-12-5.373-12-12v-8.659c0-35.745 27.1-50.034 47.579-61.516 17.561-9.845 28.324-16.541 28.324-29.579 0-17.246-21.999-28.693-39.784-28.693-23.189 0-33.894 10.977-48.942 29.969-4.057 5.12-11.46 6.071-16.666 2.124l-27.824-21.098c-5.107-3.872-6.251-11.066-2.644-16.363C184.846 131.491 214.94 112 261.794 112c49.071 0 101.45 38.304 101.45 88.8zM298 368c0 23.159-18.841 42-42 42s-42-18.841-42-42 18.841-42 42-42 42 18.841 42 42z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-05497f2\" data-id=\"05497f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cbec9f elementor-widget elementor-widget-toggle\" data-id=\"4cbec9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-8041\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8041\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Warum sind Schulungen f\u00fcr Lebensmittelsicherheit wichtig?<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8041\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8041\"><p>Der sichere Umgang mit Lebensmittel ist essenziell, denn <strong>Krankheitserreger<\/strong> k\u00f6nnen zu <strong>Lebensmittelinfektionen<\/strong> f\u00fchren, die schwere Folgen f\u00fcr Konsumenten haben k\u00f6nnen. Daher ist Lebensmittelsicherheit im <strong>Lebensmittelrecht<\/strong> verankert, welches den Konsumenten sch\u00fctzt, aber auch den Wettbewerb auf den Lebensmittelm\u00e4rkten regelt.<\/p><p>Die EU hat Lebensmittelsicherheit in <strong>verschiedenen Verordnungen<\/strong> verankert, um Lebensmittel sicherzumachen und eine gro\u00dffl\u00e4chige Umsetzung zu garantieren.<\/p><p>Damit Sie hier den \u00dcberblick bewahren, haben unsere <strong>Experten spezielle Schulungen f\u00fcr Lebensmittelsicherheit<\/strong>\u00a0f\u00fcr Sie und Ihren Betrieb entwickelt.<\/p><p>Sie m\u00f6chten mehr \u00fcber <a href=\"https:\/\/praxistrainings-lms.de\/produkt\/schulung-lebensmittelrecht\/\">Lebensmittelrecht<\/a> oder <a href=\"https:\/\/praxistrainings-lms.de\/produkt\/lebensmittelsicherheitskultur-food-safety-culture\/\">Lebensmittelsicherheit<\/a> erfahren? Wir freuen uns, Sie in unseren Schulungen zu informieren!<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-8042\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8042\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Erhalte ich nach Abschluss der E-Learnings ein g\u00fcltiges Zertifikat?<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8042\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8042\"><p>F\u00fcr unsere E-Learnings erhalten Sie direkt nach Abschluss g\u00fcltige Zertifikate und Teilnahmebest\u00e4tigungen.<\/p><p>&gt;&gt; Buchen Sie jetzt ihre <a href=\"https:\/\/praxistrainings-lms.de\/produkt\/lebensmittelhygiene-schulung\/\">Lebensmittelhygiene-Schulung<\/a>, <a href=\"https:\/\/praxistrainings-lms.de\/produkt\/e-learning-allergen-schulung\/\">Allergen-Schulung<\/a> oder Ihren Kurs zum <a href=\"https:\/\/praxistrainings-lms.de\/produkt\/e-learning-arbeitsschutz-schulung\/\">Arbeitsschutz<\/a>!<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-8043\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-8043\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Sind die Online-Kurse von Food Safety Experten entwickelt worden?<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8043\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-8043\"><p>Unsere E-Learnings wurden von Lebensmittelsicherheits-Experten entwickelt und werden regelm\u00e4\u00dfig gepr\u00fcft und aktualisiert. Die Aktualit\u00e4t der Inhalte liegt uns besonders am Herzen.<\/p><p>&gt;&gt; Buchen Sie jetzt einen unserer Kurse mit Schwerpunkten f\u00fcr <a href=\"https:\/\/praxistrainings-lms.de\/schulungen-gastronomie\/\">Gastronomie &amp; Catering<\/a> oder f\u00fcr <a href=\"https:\/\/praxistrainings-lms.de\/schulungen-lebensmittelunternehmen\/\">Lebensmittelhersteller<\/a>!<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-8044\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-8044\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Kann ich auch Gruppen-Kurse oder vor Ort Kurse buchen?<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8044\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-8044\"><p>Sie m\u00f6chten mehrere Mitarbeiter schulen? Gerne machen wir Ihnen ein individuelles Angebot f\u00fcr Gruppenkurse, schreiben Sie uns gerne eine <a href=\"mailto:info@praxistrainings-lms.de\">Nachricht<\/a>!<\/p><p>Sie m\u00f6chten die Schulung lieber vor Ort veranstalten? Gerne kommen wir in Ihren Betrieb, nehmen Sie gerne <a href=\"mailto:elearning@praxistrainings-lms.de\">Kontakt<\/a> zu uns auf!<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Warum sind Schulungen f\\u00fcr Lebensmittelsicherheit wichtig?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Der sichere Umgang mit Lebensmittel ist essenziell, denn <strong>Krankheitserreger<\\\/strong> k\\u00f6nnen zu <strong>Lebensmittelinfektionen<\\\/strong> f\\u00fchren, die schwere Folgen f\\u00fcr Konsumenten haben k\\u00f6nnen. Daher ist Lebensmittelsicherheit im <strong>Lebensmittelrecht<\\\/strong> verankert, welches den Konsumenten sch\\u00fctzt, aber auch den Wettbewerb auf den Lebensmittelm\\u00e4rkten regelt.<\\\/p><p>Die EU hat Lebensmittelsicherheit in <strong>verschiedenen Verordnungen<\\\/strong> verankert, um Lebensmittel sicherzumachen und eine gro\\u00dffl\\u00e4chige Umsetzung zu garantieren.<\\\/p><p>Damit Sie hier den \\u00dcberblick bewahren, haben unsere <strong>Experten spezielle Schulungen f\\u00fcr Lebensmittelsicherheit<\\\/strong>\\u00a0f\\u00fcr Sie und Ihren Betrieb entwickelt.<\\\/p><p>Sie m\\u00f6chten mehr \\u00fcber <a href=\\\"https:\\\/\\\/praxistrainings-lms.de\\\/produkt\\\/schulung-lebensmittelrecht\\\/\\\">Lebensmittelrecht<\\\/a> oder <a href=\\\"https:\\\/\\\/praxistrainings-lms.de\\\/produkt\\\/lebensmittelsicherheitskultur-food-safety-culture\\\/\\\">Lebensmittelsicherheit<\\\/a> erfahren? Wir freuen uns, Sie in unseren Schulungen zu informieren!<\\\/p><p>\\u00a0<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Erhalte ich nach Abschluss der E-Learnings ein g\\u00fcltiges Zertifikat?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>F\\u00fcr unsere E-Learnings erhalten Sie direkt nach Abschluss g\\u00fcltige Zertifikate und Teilnahmebest\\u00e4tigungen.<\\\/p><p>&gt;&gt; Buchen Sie jetzt ihre <a href=\\\"https:\\\/\\\/praxistrainings-lms.de\\\/produkt\\\/lebensmittelhygiene-schulung\\\/\\\">Lebensmittelhygiene-Schulung<\\\/a>, <a href=\\\"https:\\\/\\\/praxistrainings-lms.de\\\/produkt\\\/e-learning-allergen-schulung\\\/\\\">Allergen-Schulung<\\\/a> oder Ihren Kurs zum <a href=\\\"https:\\\/\\\/praxistrainings-lms.de\\\/produkt\\\/e-learning-arbeitsschutz-schulung\\\/\\\">Arbeitsschutz<\\\/a>!<\\\/p><p>\\u00a0<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Sind die Online-Kurse von Food Safety Experten entwickelt worden?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Unsere E-Learnings wurden von Lebensmittelsicherheits-Experten entwickelt und werden regelm\\u00e4\\u00dfig gepr\\u00fcft und aktualisiert. Die Aktualit\\u00e4t der Inhalte liegt uns besonders am Herzen.<\\\/p><p>&gt;&gt; Buchen Sie jetzt einen unserer Kurse mit Schwerpunkten f\\u00fcr <a href=\\\"https:\\\/\\\/praxistrainings-lms.de\\\/schulungen-gastronomie\\\/\\\">Gastronomie &amp; Catering<\\\/a> oder f\\u00fcr <a href=\\\"https:\\\/\\\/praxistrainings-lms.de\\\/schulungen-lebensmittelunternehmen\\\/\\\">Lebensmittelhersteller<\\\/a>!<\\\/p><p>\\u00a0<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Kann ich auch Gruppen-Kurse oder vor Ort Kurse buchen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Sie m\\u00f6chten mehrere Mitarbeiter schulen? Gerne machen wir Ihnen ein individuelles Angebot f\\u00fcr Gruppenkurse, schreiben Sie uns gerne eine <a href=\\\"mailto:info@praxistrainings-lms.de\\\">Nachricht<\\\/a>!<\\\/p><p>Sie m\\u00f6chten die Schulung lieber vor Ort veranstalten? Gerne kommen wir in Ihren Betrieb, nehmen Sie gerne <a href=\\\"mailto:elearning@praxistrainings-lms.de\\\">Kontakt<\\\/a> zu uns auf!<\\\/p><p>\\u00a0<\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c16845 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c16845\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2727ef\" data-id=\"a2727ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09b6066 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"09b6066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f416085 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f416085\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d1ba53b\" data-id=\"d1ba53b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-576afae elementor-widget elementor-widget-heading\" data-id=\"576afae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Klimaneutral, verantwortungsvoll und vernetzt<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a414af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a414af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c957f71\" data-id=\"c957f71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a87d427 elementor-widget elementor-widget-text-editor\" data-id=\"a87d427\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Praxistrainings-LMS arbeitet <span style=\"color: #c6c500;\"><b>verantwortungsvoll<\/b><\/span> und <span style=\"color: #c6c500;\"><b>vernetzt<\/b><\/span>.<\/p>\n<p>Wir sind Teil der<\/p>\n<ul>\n<li>CPM Food Safety Senior EXPERTs<\/li>\n<li>Mitglied im B\u00fcndnis Klimaneutrales Weserbergland seit Gr\u00fcndung<\/li>\n<li>und Unterst\u00fctzer der Allianz f\u00fcr Entwicklung und Klima.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3f8a52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3f8a52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-62c0670\" data-id=\"62c0670\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f42b53 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4f42b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/allianz-entwicklung-klima.de\/karte\/praxistrainings-lms\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"143\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/06\/SAEK_Unterstuetzer-in_Logo_RGB_DE-300x143.jpg\" class=\"attachment-medium size-medium wp-image-42524\" alt=\"Unterstuetzer-in_Logo_Allianz-pro-Klima\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/06\/SAEK_Unterstuetzer-in_Logo_RGB_DE-300x143.jpg 300w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/06\/SAEK_Unterstuetzer-in_Logo_RGB_DE-600x286.jpg 600w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/06\/SAEK_Unterstuetzer-in_Logo_RGB_DE-1024x488.jpg 1024w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/06\/SAEK_Unterstuetzer-in_Logo_RGB_DE-768x366.jpg 768w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/06\/SAEK_Unterstuetzer-in_Logo_RGB_DE-18x9.jpg 18w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2023\/06\/SAEK_Unterstuetzer-in_Logo_RGB_DE.jpg 1485w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7a7bf0a\" data-id=\"7a7bf0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e680e9 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"7e680e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.klimaschutzagentur.org\/projekte\/klimaneutrales-weserbergland-2030\/praxistrainings-lms\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1103\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/02\/2501061-scaled.jpg\" class=\"attachment-full size-full wp-image-61537\" alt=\"Logo B\u00fcndnis klimaneutrales Weserbergland mit Zusatz\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/02\/2501061-scaled.jpg 2560w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/02\/2501061-300x129.jpg 300w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/02\/2501061-1024x441.jpg 1024w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/02\/2501061-768x331.jpg 768w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/02\/2501061-1536x662.jpg 1536w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/02\/2501061-2048x882.jpg 2048w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/02\/2501061-18x8.jpg 18w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2025\/02\/2501061-600x258.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fa2753f\" data-id=\"fa2753f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51b957a elementor-widget elementor-widget-image\" data-id=\"51b957a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cp-management.de\/ueber-uns\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/12\/CPM_certifiedExpert-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-28231\" alt=\"CPM-certified-expert\" srcset=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/12\/CPM_certifiedExpert-150x150.png 150w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/12\/CPM_certifiedExpert-300x300.png 300w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/12\/elementor\/thumbs\/CPM_certifiedExpert-q81dm8w6vu4ajbqprs0yxh15v9kvaiy6xtv1jjfe94.png 100w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/12\/CPM_certifiedExpert-12x12.png 12w, https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2021\/12\/CPM_certifiedExpert.png 335w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-040c65f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"040c65f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74a8e34\" data-id=\"74a8e34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-331c2fe elementor-widget elementor-widget-spacer\" data-id=\"331c2fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gastronomie Hygieneschulung: Schulungen f\u00fcr Gastronomie und Catering Gastronomie Hygieneschulung: LMHV \u00a7 4 Sie erhalten Ihre gesetzlich vorgeschriebene Schulung nach LMHV \u00a7 4 \u2013 flexibel als E-Learning. Ideal f\u00fcr Einzelpersonen oder Gruppen. Interaktiv und praxisnah gestaltet, sofort verf\u00fcgbar. 6 Stunden \u00b7 E-Learning \u00b7 Sofort starten \u00b7 Teilnahmezertifikat inklusive \u00b7 Gruppenbuchung m\u00f6glichJetzt buchen!Gastronomie Hygieneschulung: Lebensmittel-Allergene Erhalten Sie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-33463","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gastronomie Hygieneschulung \u27a4 Hygiene &amp; Allergene<\/title>\n<meta name=\"description\" content=\"Praxisnahe &amp; Mehrsprachige Schulungen \u2705 Gastronomie Hygieneschulung \u2705 HACCP &amp; Hygienegrundlagen \u2705 Lebensmittelrecht &amp; Allergene \u27a4 Anmelden\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/praxistrainings-lms.de\/fr\/schulungen-gastronomie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gastronomie Hygieneschulung\" \/>\n<meta property=\"og:description\" content=\"Praxisnahe &amp; Mehrsprachige Schulungen \u2705 Gastronomie Hygieneschulung \u2705 HACCP &amp; Hygienegrundlagen \u2705 Lebensmittelrecht &amp; Allergene \u27a4 Anmelden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/praxistrainings-lms.de\/fr\/schulungen-gastronomie\/\" \/>\n<meta property=\"og:site_name\" content=\"Praxistrainings-LMS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jennifer.ziegler.praxistraining.lms.de\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T14:39:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/elementor\/thumbs\/ld2-py4xdqmdjol8t1h0i4sxv97vb8jmid6o1721nzu0u0.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/schulungen-gastronomie\\\/\",\"url\":\"https:\\\/\\\/praxistrainings-lms.de\\\/schulungen-gastronomie\\\/\",\"name\":\"Gastronomie Hygieneschulung \u27a4 Hygiene & Allergene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/schulungen-gastronomie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/schulungen-gastronomie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/praxistrainings-lms.de\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/ld2-py4xdqmdjol8t1h0i4sxv97vb8jmid6o1721nzu0u0.jpg\",\"datePublished\":\"2022-04-05T11:48:13+00:00\",\"dateModified\":\"2026-03-25T14:39:48+00:00\",\"description\":\"Praxisnahe & Mehrsprachige Schulungen \u2705 Gastronomie Hygieneschulung \u2705 HACCP & Hygienegrundlagen \u2705 Lebensmittelrecht & Allergene \u27a4 Anmelden\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/schulungen-gastronomie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/praxistrainings-lms.de\\\/schulungen-gastronomie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/schulungen-gastronomie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/praxistrainings-lms.de\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/ld2-py4xdqmdjol8t1h0i4sxv97vb8jmid6o1721nzu0u0.jpg\",\"contentUrl\":\"https:\\\/\\\/praxistrainings-lms.de\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/ld2-py4xdqmdjol8t1h0i4sxv97vb8jmid6o1721nzu0u0.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/schulungen-gastronomie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/praxistrainings-lms.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastronomie Hygieneschulung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/#website\",\"url\":\"https:\\\/\\\/praxistrainings-lms.de\\\/\",\"name\":\"Praxistrainings-LMS\",\"description\":\"Schulungen f\u00fcr QM &amp; QS von Lebensmittel-Unternehmen\",\"publisher\":{\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/praxistrainings-lms.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/#organization\",\"name\":\"Praxistrainings-LMS\",\"url\":\"https:\\\/\\\/praxistrainings-lms.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/praxistrainings-lms.de\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/WEB_LMS_Logo_Blue-e1646829814308.png\",\"contentUrl\":\"https:\\\/\\\/praxistrainings-lms.de\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/WEB_LMS_Logo_Blue-e1646829814308.png\",\"width\":286,\"height\":143,\"caption\":\"Praxistrainings-LMS\"},\"image\":{\"@id\":\"https:\\\/\\\/praxistrainings-lms.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jennifer.ziegler.praxistraining.lms.de\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jennifer-ziegler-sichere-lm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ1DGMwNQlP9uMcX_P-_gTg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Formation hygi\u00e8ne gastronomique \u27a4 Hygi\u00e8ne &amp; allerg\u00e8nes","description":"Formation pratique &amp; multilingue \u2705 Formation hygi\u00e8ne gastronomique \u2705 HACCP &amp; bases de l&#039;hygi\u00e8ne \u2705 Loi alimentaire &amp; allerg\u00e8nes \u27a4 S&#039;inscrire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/praxistrainings-lms.de\/fr\/schulungen-gastronomie\/","og_locale":"fr_FR","og_type":"article","og_title":"Gastronomie Hygieneschulung","og_description":"Praxisnahe & Mehrsprachige Schulungen \u2705 Gastronomie Hygieneschulung \u2705 HACCP & Hygienegrundlagen \u2705 Lebensmittelrecht & Allergene \u27a4 Anmelden","og_url":"https:\/\/praxistrainings-lms.de\/fr\/schulungen-gastronomie\/","og_site_name":"Praxistrainings-LMS","article_publisher":"https:\/\/www.facebook.com\/jennifer.ziegler.praxistraining.lms.de","article_modified_time":"2026-03-25T14:39:48+00:00","og_image":[{"url":"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/elementor\/thumbs\/ld2-py4xdqmdjol8t1h0i4sxv97vb8jmid6o1721nzu0u0.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/praxistrainings-lms.de\/schulungen-gastronomie\/","url":"https:\/\/praxistrainings-lms.de\/schulungen-gastronomie\/","name":"Formation hygi\u00e8ne gastronomique \u27a4 Hygi\u00e8ne &amp; allerg\u00e8nes","isPartOf":{"@id":"https:\/\/praxistrainings-lms.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/praxistrainings-lms.de\/schulungen-gastronomie\/#primaryimage"},"image":{"@id":"https:\/\/praxistrainings-lms.de\/schulungen-gastronomie\/#primaryimage"},"thumbnailUrl":"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/elementor\/thumbs\/ld2-py4xdqmdjol8t1h0i4sxv97vb8jmid6o1721nzu0u0.jpg","datePublished":"2022-04-05T11:48:13+00:00","dateModified":"2026-03-25T14:39:48+00:00","description":"Formation pratique &amp; multilingue \u2705 Formation hygi\u00e8ne gastronomique \u2705 HACCP &amp; bases de l&#039;hygi\u00e8ne \u2705 Loi alimentaire &amp; allerg\u00e8nes \u27a4 S&#039;inscrire","breadcrumb":{"@id":"https:\/\/praxistrainings-lms.de\/schulungen-gastronomie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/praxistrainings-lms.de\/schulungen-gastronomie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/praxistrainings-lms.de\/schulungen-gastronomie\/#primaryimage","url":"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/elementor\/thumbs\/ld2-py4xdqmdjol8t1h0i4sxv97vb8jmid6o1721nzu0u0.jpg","contentUrl":"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/elementor\/thumbs\/ld2-py4xdqmdjol8t1h0i4sxv97vb8jmid6o1721nzu0u0.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/praxistrainings-lms.de\/schulungen-gastronomie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/praxistrainings-lms.de\/"},{"@type":"ListItem","position":2,"name":"Gastronomie Hygieneschulung"}]},{"@type":"WebSite","@id":"https:\/\/praxistrainings-lms.de\/#website","url":"https:\/\/praxistrainings-lms.de\/","name":"Formation pratique LMS","description":"Formation QM &amp; QS des entreprises agroalimentaires","publisher":{"@id":"https:\/\/praxistrainings-lms.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/praxistrainings-lms.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/praxistrainings-lms.de\/#organization","name":"Formation pratique LMS","url":"https:\/\/praxistrainings-lms.de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/praxistrainings-lms.de\/#\/schema\/logo\/image\/","url":"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2022\/02\/WEB_LMS_Logo_Blue-e1646829814308.png","contentUrl":"https:\/\/praxistrainings-lms.de\/wp-content\/uploads\/2022\/02\/WEB_LMS_Logo_Blue-e1646829814308.png","width":286,"height":143,"caption":"Praxistrainings-LMS"},"image":{"@id":"https:\/\/praxistrainings-lms.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jennifer.ziegler.praxistraining.lms.de","https:\/\/www.linkedin.com\/in\/jennifer-ziegler-sichere-lm\/","https:\/\/www.youtube.com\/channel\/UCQ1DGMwNQlP9uMcX_P-_gTg"]}]}},"_links":{"self":[{"href":"https:\/\/praxistrainings-lms.de\/fr\/wp-json\/wp\/v2\/pages\/33463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/praxistrainings-lms.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/praxistrainings-lms.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/praxistrainings-lms.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/praxistrainings-lms.de\/fr\/wp-json\/wp\/v2\/comments?post=33463"}],"version-history":[{"count":8,"href":"https:\/\/praxistrainings-lms.de\/fr\/wp-json\/wp\/v2\/pages\/33463\/revisions"}],"predecessor-version":[{"id":76752,"href":"https:\/\/praxistrainings-lms.de\/fr\/wp-json\/wp\/v2\/pages\/33463\/revisions\/76752"}],"wp:attachment":[{"href":"https:\/\/praxistrainings-lms.de\/fr\/wp-json\/wp\/v2\/media?parent=33463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}